{"id":998,"date":"2025-11-26T20:24:43","date_gmt":"2025-11-26T19:24:43","guid":{"rendered":"https:\/\/dev.smr-legal.de\/?p=998"},"modified":"2025-11-27T18:34:23","modified_gmt":"2025-11-27T17:34:23","slug":"gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit","status":"publish","type":"post","link":"https:\/\/smr-legal.de\/es\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\/","title":{"rendered":"Das \u201eGesetz zur St\u00e4rkung des Justizstandortes Deutschland durch Einf\u00fchrung von Commercial Courts und der Gerichtssprache Englisch in der Zivilgerichtsbarkeit (Justizstandort-St\u00e4rkungsgesetz)\u201c"},"content":{"rendered":"<p><\/p>\n\n\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2180,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Das \u201eGesetz zur St\u00e4rkung des Justizstandortes Deutschland durch Einf\u00fchrung von Commercial Courts und der Gerichtssprache Englisch in der Zivilgerichtsbarkeit (Justizstandort-St\u00e4rkungsgesetz)\u201c - Stroschein &amp; Makowka<\/title>\n<meta name=\"description\" content=\"Am 01.04.2025 ist das \u201eGesetz zur St\u00e4rkung des Justizstandortes Deutschland durch Einf\u00fchrung von Commercial Courts und der Gerichtssprache Englisch in der Zivilgerichtsbarkeit (Justizstandort-St\u00e4rkungsgesetz\u201c in Kraft getreten. Damit wird der \u00fcber 100 Jahre alte Grundsatz \u201eGerichtssprache ist deutsch\u201c reformiert.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smr-legal.de\/es\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Das \u201eGesetz zur St\u00e4rkung des Justizstandortes Deutschland durch Einf\u00fchrung von Commercial Courts und der Gerichtssprache Englisch in der Zivilgerichtsbarkeit (Justizstandort-St\u00e4rkungsgesetz)\u201c - Stroschein &amp; Makowka\" \/>\n<meta property=\"og:description\" content=\"Am 01.04.2025 ist das \u201eGesetz zur St\u00e4rkung des Justizstandortes Deutschland durch Einf\u00fchrung von Commercial Courts und der Gerichtssprache Englisch in der Zivilgerichtsbarkeit (Justizstandort-St\u00e4rkungsgesetz\u201c in Kraft getreten. Damit wird der \u00fcber 100 Jahre alte Grundsatz \u201eGerichtssprache ist deutsch\u201c reformiert.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smr-legal.de\/es\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\/\" \/>\n<meta property=\"og:site_name\" content=\"Stroschein &amp; Makowka\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/StroscheinMakowka\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-26T19:24:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-27T17:34:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smr-legal.de\/wp-content\/uploads\/2025\/07\/Thorsten-Makowka-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"korfmacher\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"korfmacher\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smr-legal.de\\\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smr-legal.de\\\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\\\/\"},\"author\":{\"name\":\"korfmacher\",\"@id\":\"https:\\\/\\\/smr-legal.de\\\/en\\\/#\\\/schema\\\/person\\\/eb9fadc234be05d10f9489b34c24c53e\"},\"headline\":\"Das \u201eGesetz zur St\u00e4rkung des Justizstandortes Deutschland durch Einf\u00fchrung von Commercial Courts und der Gerichtssprache Englisch in der Zivilgerichtsbarkeit (Justizstandort-St\u00e4rkungsgesetz)\u201c\",\"datePublished\":\"2025-11-26T19:24:43+00:00\",\"dateModified\":\"2025-11-27T17:34:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smr-legal.de\\\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\\\/\"},\"wordCount\":23,\"publisher\":{\"@id\":\"https:\\\/\\\/smr-legal.de\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/smr-legal.de\\\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smr-legal.de\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Thorsten-Makowka-scaled.jpg\",\"articleSection\":[\"Allgemein\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smr-legal.de\\\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\\\/\",\"url\":\"https:\\\/\\\/smr-legal.de\\\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\\\/\",\"name\":\"Das \u201eGesetz zur St\u00e4rkung des Justizstandortes Deutschland durch Einf\u00fchrung von Commercial Courts und der Gerichtssprache Englisch in der Zivilgerichtsbarkeit (Justizstandort-St\u00e4rkungsgesetz)\u201c - Stroschein &amp; Makowka\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smr-legal.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smr-legal.de\\\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smr-legal.de\\\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smr-legal.de\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Thorsten-Makowka-scaled.jpg\",\"datePublished\":\"2025-11-26T19:24:43+00:00\",\"dateModified\":\"2025-11-27T17:34:23+00:00\",\"description\":\"Am 01.04.2025 ist das \u201eGesetz zur St\u00e4rkung des Justizstandortes Deutschland durch Einf\u00fchrung von Commercial Courts und der Gerichtssprache Englisch in der Zivilgerichtsbarkeit (Justizstandort-St\u00e4rkungsgesetz\u201c in Kraft getreten. Damit wird der \u00fcber 100 Jahre alte Grundsatz \u201eGerichtssprache ist deutsch\u201c reformiert.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smr-legal.de\\\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smr-legal.de\\\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/smr-legal.de\\\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smr-legal.de\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Thorsten-Makowka-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/smr-legal.de\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Thorsten-Makowka-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smr-legal.de\\\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/smr-legal.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Das \u201eGesetz zur St\u00e4rkung des Justizstandortes Deutschland durch Einf\u00fchrung von Commercial Courts und der Gerichtssprache Englisch in der Zivilgerichtsbarkeit (Justizstandort-St\u00e4rkungsgesetz)\u201c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smr-legal.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/smr-legal.de\\\/en\\\/\",\"name\":\"Stroschein & Makowka\",\"description\":\"Fachanw\u00e4lte f\u00fcr Handels- und Gesellschaftsrecht &amp; Internationales Wirtschaftsrecht\",\"publisher\":{\"@id\":\"https:\\\/\\\/smr-legal.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smr-legal.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/smr-legal.de\\\/en\\\/#organization\",\"name\":\"Stroschein & Makowka Partnerschaftsgesellschaft mbB\",\"url\":\"https:\\\/\\\/smr-legal.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/smr-legal.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/smr-legal.de\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logo-sm-gr.png\",\"contentUrl\":\"https:\\\/\\\/smr-legal.de\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logo-sm-gr.png\",\"width\":2200,\"height\":550,\"caption\":\"Stroschein & Makowka Partnerschaftsgesellschaft mbB\"},\"image\":{\"@id\":\"https:\\\/\\\/smr-legal.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/StroscheinMakowka\",\"https:\\\/\\\/www.instagram.com\\\/stroscheinmakowka\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smr-legal.de\\\/en\\\/#\\\/schema\\\/person\\\/eb9fadc234be05d10f9489b34c24c53e\",\"name\":\"korfmacher\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/246a59d0936fd5f65d43a70dd3c7f5748faebbfb3df8a606a8816359e6293358?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/246a59d0936fd5f65d43a70dd3c7f5748faebbfb3df8a606a8816359e6293358?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/246a59d0936fd5f65d43a70dd3c7f5748faebbfb3df8a606a8816359e6293358?s=96&d=mm&r=g\",\"caption\":\"korfmacher\"},\"sameAs\":[\"https:\\\/\\\/smr-legal.de\",\"https:\\\/\\\/www.instagram.com\\\/takecare\\\/\"],\"url\":\"https:\\\/\\\/smr-legal.de\\\/es\\\/author\\\/korfmacher\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Das \u201eGesetz zur St\u00e4rkung des Justizstandortes Deutschland durch Einf\u00fchrung von Commercial Courts und der Gerichtssprache Englisch in der Zivilgerichtsbarkeit (Justizstandort-St\u00e4rkungsgesetz)\u201c - Stroschein &amp; Makowka","description":"Am 01.04.2025 ist das \u201eGesetz zur St\u00e4rkung des Justizstandortes Deutschland durch Einf\u00fchrung von Commercial Courts und der Gerichtssprache Englisch in der Zivilgerichtsbarkeit (Justizstandort-St\u00e4rkungsgesetz\u201c in Kraft getreten. Damit wird der \u00fcber 100 Jahre alte Grundsatz \u201eGerichtssprache ist deutsch\u201c reformiert.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smr-legal.de\/es\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\/","og_locale":"es_ES","og_type":"article","og_title":"Das \u201eGesetz zur St\u00e4rkung des Justizstandortes Deutschland durch Einf\u00fchrung von Commercial Courts und der Gerichtssprache Englisch in der Zivilgerichtsbarkeit (Justizstandort-St\u00e4rkungsgesetz)\u201c - Stroschein &amp; Makowka","og_description":"Am 01.04.2025 ist das \u201eGesetz zur St\u00e4rkung des Justizstandortes Deutschland durch Einf\u00fchrung von Commercial Courts und der Gerichtssprache Englisch in der Zivilgerichtsbarkeit (Justizstandort-St\u00e4rkungsgesetz\u201c in Kraft getreten. Damit wird der \u00fcber 100 Jahre alte Grundsatz \u201eGerichtssprache ist deutsch\u201c reformiert.","og_url":"https:\/\/smr-legal.de\/es\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\/","og_site_name":"Stroschein &amp; Makowka","article_publisher":"https:\/\/www.facebook.com\/StroscheinMakowka","article_published_time":"2025-11-26T19:24:43+00:00","article_modified_time":"2025-11-27T17:34:23+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/smr-legal.de\/wp-content\/uploads\/2025\/07\/Thorsten-Makowka-scaled.jpg","type":"image\/jpeg"}],"author":"korfmacher","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"korfmacher","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smr-legal.de\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\/#article","isPartOf":{"@id":"https:\/\/smr-legal.de\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\/"},"author":{"name":"korfmacher","@id":"https:\/\/smr-legal.de\/en\/#\/schema\/person\/eb9fadc234be05d10f9489b34c24c53e"},"headline":"Das \u201eGesetz zur St\u00e4rkung des Justizstandortes Deutschland durch Einf\u00fchrung von Commercial Courts und der Gerichtssprache Englisch in der Zivilgerichtsbarkeit (Justizstandort-St\u00e4rkungsgesetz)\u201c","datePublished":"2025-11-26T19:24:43+00:00","dateModified":"2025-11-27T17:34:23+00:00","mainEntityOfPage":{"@id":"https:\/\/smr-legal.de\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\/"},"wordCount":23,"publisher":{"@id":"https:\/\/smr-legal.de\/en\/#organization"},"image":{"@id":"https:\/\/smr-legal.de\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\/#primaryimage"},"thumbnailUrl":"https:\/\/smr-legal.de\/wp-content\/uploads\/2025\/07\/Thorsten-Makowka-scaled.jpg","articleSection":["Allgemein"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/smr-legal.de\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\/","url":"https:\/\/smr-legal.de\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\/","name":"Das \u201eGesetz zur St\u00e4rkung des Justizstandortes Deutschland durch Einf\u00fchrung von Commercial Courts und der Gerichtssprache Englisch in der Zivilgerichtsbarkeit (Justizstandort-St\u00e4rkungsgesetz)\u201c - Stroschein &amp; Makowka","isPartOf":{"@id":"https:\/\/smr-legal.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smr-legal.de\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\/#primaryimage"},"image":{"@id":"https:\/\/smr-legal.de\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\/#primaryimage"},"thumbnailUrl":"https:\/\/smr-legal.de\/wp-content\/uploads\/2025\/07\/Thorsten-Makowka-scaled.jpg","datePublished":"2025-11-26T19:24:43+00:00","dateModified":"2025-11-27T17:34:23+00:00","description":"Am 01.04.2025 ist das \u201eGesetz zur St\u00e4rkung des Justizstandortes Deutschland durch Einf\u00fchrung von Commercial Courts und der Gerichtssprache Englisch in der Zivilgerichtsbarkeit (Justizstandort-St\u00e4rkungsgesetz\u201c in Kraft getreten. Damit wird der \u00fcber 100 Jahre alte Grundsatz \u201eGerichtssprache ist deutsch\u201c reformiert.","breadcrumb":{"@id":"https:\/\/smr-legal.de\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smr-legal.de\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/smr-legal.de\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\/#primaryimage","url":"https:\/\/smr-legal.de\/wp-content\/uploads\/2025\/07\/Thorsten-Makowka-scaled.jpg","contentUrl":"https:\/\/smr-legal.de\/wp-content\/uploads\/2025\/07\/Thorsten-Makowka-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/smr-legal.de\/gesetz-zur-staerkung-des-justizstandortes-deutschland-durch-einfuehrung-von-commercial-courts-und-der-gerichtssprache-englisch-in-der-zivilgerichtsbarkeit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/smr-legal.de\/"},{"@type":"ListItem","position":2,"name":"Das \u201eGesetz zur St\u00e4rkung des Justizstandortes Deutschland durch Einf\u00fchrung von Commercial Courts und der Gerichtssprache Englisch in der Zivilgerichtsbarkeit (Justizstandort-St\u00e4rkungsgesetz)\u201c"}]},{"@type":"WebSite","@id":"https:\/\/smr-legal.de\/en\/#website","url":"https:\/\/smr-legal.de\/en\/","name":"Stroschein & Makowka","description":"Despacho de Abogados Especialistas en Derecho de Sociedades, Corporativo Internacional, Comercial y Mercantil","publisher":{"@id":"https:\/\/smr-legal.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smr-legal.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/smr-legal.de\/en\/#organization","name":"Stroschein &amp; Makowka Partnerschaftsgesellschaft mbB","url":"https:\/\/smr-legal.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/smr-legal.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/smr-legal.de\/wp-content\/uploads\/2024\/04\/logo-sm-gr.png","contentUrl":"https:\/\/smr-legal.de\/wp-content\/uploads\/2024\/04\/logo-sm-gr.png","width":2200,"height":550,"caption":"Stroschein & Makowka Partnerschaftsgesellschaft mbB"},"image":{"@id":"https:\/\/smr-legal.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/StroscheinMakowka","https:\/\/www.instagram.com\/stroscheinmakowka\/"]},{"@type":"Person","@id":"https:\/\/smr-legal.de\/en\/#\/schema\/person\/eb9fadc234be05d10f9489b34c24c53e","name":"korfmacher","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/246a59d0936fd5f65d43a70dd3c7f5748faebbfb3df8a606a8816359e6293358?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/246a59d0936fd5f65d43a70dd3c7f5748faebbfb3df8a606a8816359e6293358?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/246a59d0936fd5f65d43a70dd3c7f5748faebbfb3df8a606a8816359e6293358?s=96&d=mm&r=g","caption":"korfmacher"},"sameAs":["https:\/\/smr-legal.de","https:\/\/www.instagram.com\/takecare\/"],"url":"https:\/\/smr-legal.de\/es\/author\/korfmacher\/"}]}},"_links":{"self":[{"href":"https:\/\/smr-legal.de\/es\/wp-json\/wp\/v2\/posts\/998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smr-legal.de\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smr-legal.de\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smr-legal.de\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smr-legal.de\/es\/wp-json\/wp\/v2\/comments?post=998"}],"version-history":[{"count":16,"href":"https:\/\/smr-legal.de\/es\/wp-json\/wp\/v2\/posts\/998\/revisions"}],"predecessor-version":[{"id":2252,"href":"https:\/\/smr-legal.de\/es\/wp-json\/wp\/v2\/posts\/998\/revisions\/2252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smr-legal.de\/es\/wp-json\/wp\/v2\/media\/2180"}],"wp:attachment":[{"href":"https:\/\/smr-legal.de\/es\/wp-json\/wp\/v2\/media?parent=998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smr-legal.de\/es\/wp-json\/wp\/v2\/categories?post=998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smr-legal.de\/es\/wp-json\/wp\/v2\/tags?post=998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}