{"id":3,"date":"2024-01-03T04:51:43","date_gmt":"2024-01-03T03:51:43","guid":{"rendered":"https:\/\/dev.smr-legal.de\/?page_id=3"},"modified":"2025-05-06T02:02:12","modified_gmt":"2025-05-06T00:02:12","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/smr-legal.de\/ru\/datenschutzerklaerung\/","title":{"rendered":"Data Protection"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3\" class=\"elementor elementor-3\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e48340c elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"6e48340c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-976d5fa elementor-toc--content-ellipsis elementor-toc--minimized-on-tablet elementor-widget elementor-widget-table-of-contents\" data-id=\"976d5fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;exclude_headings_by_selector&quot;:[],&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet_extra&quot;,&quot;tablet&quot;],&quot;sticky_offset_laptop&quot;:110,&quot;marker_view&quot;:&quot;bullets&quot;,&quot;icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;no_headings_message&quot;:&quot;No headings were found on this page.&quot;,&quot;headings_by_tags&quot;:[&quot;h2&quot;,&quot;h3&quot;,&quot;h4&quot;,&quot;h5&quot;,&quot;h6&quot;],&quot;minimize_box&quot;:&quot;yes&quot;,&quot;minimized_on&quot;:&quot;tablet&quot;,&quot;hierarchical_view&quot;:&quot;yes&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t\t\t\t<h4 class=\"elementor-toc__header-title\">\n\t\t\t\tTable of Contents\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--expand\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__976d5fa\" aria-expanded=\"true\" aria-label=\"Abrir la tabla de contenidos\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/div>\n\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--collapse\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__976d5fa\" aria-expanded=\"true\" aria-label=\"Cerrar la tabla de contenidos\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"elementor-toc__976d5fa\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<svg class=\"elementor-toc__spinner eicon-animation-spin e-font-icon-svg e-eicon-loading\" aria-hidden=\"true\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M500 975V858C696 858 858 696 858 500S696 142 500 142 142 304 142 500H25C25 237 238 25 500 25S975 237 975 500 763 975 500 975Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2244c50 e-flex e-con-boxed e-con e-parent\" data-id=\"2244c50\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bcd7851 e-flex e-con-boxed e-con e-child\" data-id=\"bcd7851\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0c75824 elementor-widget elementor-widget-heading\" data-id=\"0c75824\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1. Information \u00fcber die Erhebung personenbezogener Daten. \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-75545d5 e-flex e-con-boxed e-con e-child\" data-id=\"75545d5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b3ff99 elementor-widget elementor-widget-heading\" data-id=\"1b3ff99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Verantwortlicher gem. Art. 4 Abs. 7 der europ\u00e4ischen Datenschutz-Grundverordnung (DSGVO) ist:<\/span>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bc0568 elementor-widget elementor-widget-heading\" data-id=\"8bc0568\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Stroschein &amp; Makowka Rechtsanw\u00e4lte PartG mbB\n\n<\/span>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9205e0d elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9205e0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/maps.app.goo.gl\/aDycQcgU2KL973uZ6\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"23\" viewBox=\"0 0 17 23\" fill=\"none\"><path d=\"M8.49962 5.40735C7.88097 5.40735 7.2762 5.59186 6.76181 5.93754C6.24742 6.28322 5.8465 6.77456 5.60975 7.3494C5.373 7.92425 5.31105 8.5568 5.43175 9.16706C5.55244 9.77732 5.85035 10.3379 6.28781 10.7778C6.72526 11.2178 7.28262 11.5174 7.88938 11.6388C8.49615 11.7602 9.12508 11.6979 9.69665 11.4598C10.2682 11.2217 10.7567 10.8185 11.1004 10.3011C11.4441 9.78377 11.6276 9.17553 11.6276 8.55331C11.6267 7.71924 11.2968 6.91961 10.7104 6.32983C10.124 5.74005 9.32892 5.4083 8.49962 5.40735ZM8.49962 10.1263C8.19029 10.1263 7.88791 10.034 7.63072 9.8612C7.37352 9.68836 7.17306 9.44269 7.05468 9.15527C6.93631 8.86784 6.90534 8.55157 6.96568 8.24644C7.02603 7.94131 7.17499 7.66103 7.39372 7.44105C7.61244 7.22106 7.89112 7.07125 8.1945 7.01055C8.49789 6.94986 8.81235 6.98101 9.09813 7.10007C9.38392 7.21912 9.62818 7.42074 9.80003 7.67941C9.97189 7.93809 10.0636 8.24221 10.0636 8.55331C10.0631 8.97035 9.8982 9.37016 9.605 9.66505C9.3118 9.95994 8.91427 10.1258 8.49962 10.1263Z\" fill=\"#333333\"><\/path><path d=\"M14.5103 2.50326C13.0242 1.00895 11.0403 0.121266 8.94172 0.0115376C6.84309 -0.098191 4.77844 0.577813 3.14624 1.90908C1.51404 3.24035 0.429999 5.1325 0.103345 7.22036C-0.223309 9.30821 0.230576 11.4438 1.3774 13.2148L7.28669 22.3388C7.41819 22.5418 7.598 22.7086 7.8098 22.8241C8.02161 22.9395 8.25872 23 8.49964 23C8.74056 23 8.97766 22.9395 9.18947 22.8241C9.40128 22.7086 9.58108 22.5418 9.71258 22.3388L15.6221 13.2148C16.6862 11.5719 17.1565 9.61102 16.954 7.66084C16.7516 5.71067 15.8889 3.88974 14.5103 2.50326ZM14.3116 12.3562L8.49966 21.3296L2.68763 12.3562C0.908595 9.60946 1.29016 5.93359 3.59489 3.61551C4.23899 2.96769 5.00365 2.45381 5.84521 2.10321C6.68677 1.75261 7.58876 1.57216 8.49966 1.57216C9.41056 1.57216 10.3125 1.75261 11.1541 2.10321C11.9957 2.45381 12.7603 2.96769 13.4044 3.61551C15.7092 5.93359 16.0907 9.60946 14.3116 12.3562Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">F\u00fcrstenwall 172<br>  F\u00fcrst &amp; Friedrich<br>40217 D\u00fcsseldorf<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:info@smr-legal.de\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M3 9.2532V16.2C3 16.9426 3.29851 17.6548 3.82986 18.1799C4.36122 18.705 5.08189 19 5.83333 19H17.1667C17.9181 19 18.6388 18.705 19.1701 18.1799C19.7015 17.6548 20 16.9426 20 16.2V7.8C20 7.05739 19.7015 6.3452 19.1701 5.8201C18.6388 5.295 17.9181 5 17.1667 5H5.83333C5.08189 5 4.36122 5.295 3.82986 5.8201C3.29851 6.3452 3 7.05739 3 7.8V9.2532ZM5.83333 6.4H17.1667C17.5424 6.4 17.9027 6.5475 18.1684 6.81005C18.4341 7.0726 18.5833 7.4287 18.5833 7.8V8.836L11.5 12.6048L4.41667 8.836V7.8C4.41667 7.4287 4.56592 7.0726 4.8316 6.81005C5.09728 6.5475 5.45761 6.4 5.83333 6.4V6.4ZM4.41667 10.4264L11.1642 14.016C11.2674 14.0709 11.3828 14.0996 11.5 14.0996C11.6172 14.0996 11.7326 14.0709 11.8358 14.016L18.5833 10.4264V16.2C18.5833 16.5713 18.4341 16.9274 18.1684 17.1899C17.9027 17.4525 17.5424 17.6 17.1667 17.6H5.83333C5.45761 17.6 5.09728 17.4525 4.8316 17.1899C4.56592 16.9274 4.41667 16.5713 4.41667 16.2V10.4264Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">info@smr-legal.de<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+4921169805033\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M10.6507 13.3435C11.6315 14.3594 12.8182 15.1438 14.1274 15.6415L15.8987 14.2022C15.9512 14.1653 16.0135 14.1455 16.0772 14.1455C16.141 14.1455 16.2032 14.1653 16.2557 14.2022L19.5445 16.366C19.6694 16.4426 19.7751 16.5479 19.8532 16.6734C19.9314 16.7989 19.9799 16.9413 19.995 17.0893C20.01 17.2372 19.9912 17.3867 19.9399 17.526C19.8886 17.6652 19.8063 17.7904 19.6996 17.8916L18.1585 19.446C17.9378 19.6687 17.6666 19.8321 17.369 19.9217C17.0714 20.0113 16.7568 20.0242 16.4531 19.9594C13.4237 19.3205 10.6315 17.8242 8.39558 15.6415C6.20924 13.4371 4.69631 10.6323 4.0403 7.56712C3.9755 7.26182 3.98903 6.9446 4.07957 6.64621C4.17012 6.34781 4.33461 6.07836 4.55711 5.86397L6.15452 4.29035C6.25337 4.18662 6.37392 4.10707 6.50714 4.05765C6.64036 4.00824 6.78281 3.99024 6.92381 4.00501C7.06481 4.01977 7.20071 4.06692 7.32134 4.14293C7.44197 4.21893 7.5442 4.32181 7.62037 4.44387L9.80975 7.75903C9.84751 7.81109 9.8679 7.87416 9.8679 7.93894C9.8679 8.00372 9.84751 8.06679 9.80975 8.11885L8.36739 9.88917C8.86803 11.1994 9.64801 12.3793 10.6507 13.3435V13.3435Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+49 211 698050-33<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-245e3b3 elementor-widget elementor-widget-heading\" data-id=\"245e3b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">(nachfolgend \u201e<b>S&amp;M<\/b>\u201c oder \u201e<b>wir<\/b>\u201c)<\/span>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba841be elementor-widget elementor-widget-text-editor\" data-id=\"ba841be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tBei Ihrer Kontaktaufnahme mit uns per E-Mail werden die von Ihnen mitgeteilten Daten (Ihre E-Mail-Adresse, ggf. Ihr Name und Ihre Telefonnummer) von uns gespeichert, um Ihre Fragen zu beantworten. Die in diesem Zusammenhang anfallenden Daten l\u00f6schen wir, nachdem die Speicherung nicht mehr erforderlich ist, oder schr\u00e4nken die Verarbeitung ein, falls gesetzliche Aufbewahrungspflichten bestehen.\n\nFalls wir f\u00fcr einzelne Funktionen unseres Angebots auf beauftragte Dienstleister zur\u00fcckgreifen oder Ihre Daten f\u00fcr werbliche Zwecke nutzen m\u00f6chten, werden wir Sie untenstehend im Detail \u00fcber die jeweiligen Vorg\u00e4nge informieren. Dabei nennen wir auch die festgelegten Kriterien der Speicherdauer.\n\nDie von uns verarbeiteten Daten werden nach Ma\u00dfgabe der Art. 17 und 18 DSGVO gel\u00f6scht oder in ihrer Verarbeitung eingeschr\u00e4nkt. Sofern nicht im Rahmen dieser Datenschutzerkl\u00e4rung ausdr\u00fccklich angegeben, werden die bei uns gespeicherten Daten gel\u00f6scht, sobald sie f\u00fcr ihre Zweckbestimmung nicht mehr erforderlich sind und der L\u00f6schung keine gesetzlichen Aufbewahrungspflichten entgegenstehen. Sofern die Daten nicht gel\u00f6scht werden, weil sie f\u00fcr andere und gesetzlich zul\u00e4ssige Zwecke erforderlich sind, wird deren Verarbeitung eingeschr\u00e4nkt. Das bedeutet, die Daten werden gesperrt und nicht f\u00fcr andere Zwecke verarbeitet. Das gilt z.B. f\u00fcr Daten, die aus handels- oder steuerrechtlichen Gr\u00fcnden aufbewahrt werden m\u00fcssen.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e69a1c e-flex e-con-boxed e-con e-parent\" data-id=\"7e69a1c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-82f8111 e-flex e-con-boxed e-con e-child\" data-id=\"82f8111\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b95f7a8 elementor-widget elementor-widget-heading\" data-id=\"b95f7a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2. Ihre Rechte<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e09963b e-flex e-con-boxed e-con e-child\" data-id=\"e09963b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-79c4c29 elementor-widget elementor-widget-text-editor\" data-id=\"79c4c29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Die von uns verarbeiteten Daten werden nach Ma\u00dfgabe der Art. 17 und 18 DSGVO gel\u00f6scht oder in ihrer Verarbeitung eingeschr\u00e4nkt. Sofern nicht im Rahmen dieser Datenschutzerkl\u00e4rung ausdr\u00fccklich angegeben, werden die bei uns gespeicherten Daten gel\u00f6scht, sobald sie f\u00fcr ihre Zweckbestimmung nicht mehr erforderlich sind und der L\u00f6schung keine gesetzlichen Aufbewahrungspflichten entgegenstehen. Sofern die Daten nicht gel\u00f6scht werden, weil sie f\u00fcr andere und gesetzlich zul\u00e4ssige Zwecke erforderlich sind, wird deren Verarbeitung eingeschr\u00e4nkt. Das bedeutet, die Daten werden gesperrt und nicht f\u00fcr andere Zwecke verarbeitet. Das gilt z.B. f\u00fcr Daten, die aus handels- oder steuerrechtlichen Gr\u00fcnden aufbewahrt werden m\u00fcssen.<\/p>\n<p>Sie haben uns gegen\u00fcber betreffend Ihre personenbezogenen Daten das Recht:<\/p>\n<p>\u00a0<\/p>\n<ul>\n<li>auf Auskunft \u00fcber die von uns zu Ihrer Person verarbeiteten personenbezogenen Daten. Bei einer Auskunftsanfrage, die nicht schriftlich erfolgt, bitten wir um Verst\u00e4ndnis daf\u00fcr, dass wir dann ggf. Nachweise von Ihnen verlangen, die belegen, dass Sie die Person sind, f\u00fcr die Sie sich ausgeben;<\/li>\n<li>auf Berichtigung oder L\u00f6schung oder auf Einschr\u00e4nkung der Verarbeitung, soweit Ihnen dies gesetzlich zusteht. Zudem haben Sie ein Widerspruchsrecht gegen die Verarbeitung im Rahmen der gesetzlichen Vorgaben. Gleiches gilt f\u00fcr ein Recht auf Daten\u00fcbertragbarkeit und<\/li>\n<li>sich bei Beschwerden \u00fcber die Verarbeitung Ihrer personenbezogenen Daten an eine Aufsichtsbeh\u00f6rde zu wenden, beispielsweise an den f\u00fcr uns zust\u00e4ndigen Landesbeauftragten f\u00fcr Datenschutz und Informationsfreiheit Nordrhein-Westfalen (<a href=\"https:\/\/www.ldi.nrw.de\/\" target=\"_blank\" rel=\"nofollow noopener\">https:\/\/www.ldi.nrw.de<\/a>).<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f49a34c e-flex e-con-boxed e-con e-parent\" data-id=\"f49a34c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-555a229 e-flex e-con-boxed e-con e-child\" data-id=\"555a229\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-040e8f4 elementor-widget elementor-widget-heading\" data-id=\"040e8f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3. Erhebung personenbezogener Daten bei Besuch unserer Website<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-760b7e4 e-flex e-con-boxed e-con e-child\" data-id=\"760b7e4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ff2a26 elementor-widget elementor-widget-text-editor\" data-id=\"4ff2a26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Bei der blo\u00df informatorischen Nutzung der Website, also wenn Sie sich nicht registrieren oder uns anderweitig Informationen \u00fcbermitteln, erheben wir nur die personenbezogenen Daten, die Ihr Browser an unseren Server \u00fcbermittelt. Wenn Sie unsere Website betrachten m\u00f6chten, erheben wir die folgenden Daten, die f\u00fcr uns technisch erforderlich sind, um Ihnen unsere Website anzuzeigen und die Stabilit\u00e4t und Sicherheit zu gew\u00e4hrleisten (Rechtsgrundlage ist Art. 6 Abs. 1 S. 1 lit. f DS-GVO):<\/p>\n<ul>\n<li>IP-Adresse<\/li>\n<li>Datum und Uhrzeit der Anfrage<\/li>\n<li>Zeitzonendifferenz zur Greenwich Mean Time (GMT)<\/li>\n<li>Inhalt der Anforderung (konkret aufgerufene Seite)<\/li>\n<li>Zugriffsstatus\/HTTP-Statuscode<\/li>\n<li>jeweils \u00fcbertragene Datenmenge<\/li>\n<li>Website, von der die Anforderung kommt<\/li>\n<li>Browser<\/li>\n<li>Betriebssystem und dessen Oberfl\u00e4che<\/li>\n<li>Sprache und Version der Browsersoftware<\/li>\n<\/ul>\n<div>\u00a0<\/div>\n<p>Diese Daten werden aus Sicherheitsgr\u00fcnden (z.B. zur Aufkl\u00e4rung von Missbrauchs- oder Betrugshandlungen) f\u00fcr die Dauer von maximal sieben (7) Tagen gespeichert und danach gel\u00f6scht. Daten, deren weitere Aufbewahrung zu Beweiszwecken erforderlich ist, sind bis zur endg\u00fcltigen Kl\u00e4rung des jeweiligen Vorfalls von der L\u00f6schung ausgenommen.<\/p>\n<p>Zus\u00e4tzlich zu den zuvor genannten Daten werden bei Ihrer Nutzung unserer Website Cookies auf Ihrem Rechner gespeichert. Bei Cookies handelt es sich um kleine Textdateien, die auf Ihrer Festplatte dem von Ihnen verwendeten Browser zugeordnet gespeichert werden und durch welche der Stelle, die den Cookie setzt (hier durch uns), bestimmte Informationen zuflie\u00dfen. Cookies k\u00f6nnen keine Programme ausf\u00fchren oder Viren auf Ihren Computer \u00fcbertragen. Sie dienen dazu, das Internetangebot insgesamt nutzerfreundlicher und effektiver zu machen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c99848 elementor-widget elementor-widget-heading\" data-id=\"7c99848\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Einsatz von Cookies:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e1f04c elementor-widget elementor-widget-text-editor\" data-id=\"9e1f04c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Diese Website nutzt transiente- und persistente Cookies:<\/p><p>Transiente Cookies werden automatisiert gel\u00f6scht, wenn Sie den Browser schlie\u00dfen. Dazu z\u00e4hlen insbesondere die Session-Cookies. Diese speichern eine sogenannte Session-ID, mit welcher sich verschiedene Anfragen Ihres Browsers der gemeinsamen Sitzung zuordnen lassen. Dadurch kann Ihr Rechner wiedererkannt werden, wenn Sie auf unsere Website zur\u00fcckkehren. Die Session-Cookies werden gel\u00f6scht, wenn Sie den Browser schlie\u00dfen.<\/p><p>Persistente Cookies werden automatisiert nach einer vorgegebenen Dauer gel\u00f6scht, die sich je nach Cookie unterscheiden kann. Sie k\u00f6nnen die Cookies in den Sicherheitseinstellungen Ihres Browsers jederzeit l\u00f6schen.<\/p><p>Sie k\u00f6nnen Ihre Browser-Einstellung entsprechend Ihren W\u00fcnschen konfigurieren und z. B. die Annahme von Third-Party-Cookies oder allen Cookies ablehnen. Wir weisen Sie darauf hin, dass Sie eventuell nicht alle Funktionen dieser Website nutzen k\u00f6nnen.<\/p><p>\u00a0<\/p><p>Zur Verwaltung der eingesetzten Cookies und \u00e4hnlichen Technologien (Tracking-Pixel, Web-Beacons etc.) und diesbez\u00fcglicher Einwilligungen setzen wir das Consent Tool &#8222;Real Cookie Banner&#8220; ein. Details zur Funktionsweise von &#8222;Real Cookie Banner&#8220; finden Sie\u00a0 unter\u00a0 <a href=\"https:\/\/devowl.io\/de\/rcb\/datenverarbeitung\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/devowl.io\/de\/rcb\/datenverarbeitung\/<\/a>.<\/p><p>Rechtsgrundlagen f\u00fcr die Verarbeitung von personenbezogenen Daten in diesem Zusammenhang sind Art. 6 Abs. 1 lit. c DS-GVO und Art. 6 Abs. 1 lit. f DS-GVO. Unser berechtigtes Interesse ist die Verwaltung der eingesetzten Cookies und \u00e4hnlichen Technologien und der diesbez\u00fcglichen Einwilligungen.<\/p><p>Die Bereitstellung der personenbezogenen Daten ist weder vertraglich vorgeschrieben noch f\u00fcr den Abschluss eines Vertrages notwendig. Du bist nicht verpflichtet die personenbezogenen Daten bereitzustellen. Wenn du die personenbezogenen Daten nicht bereitstellst, k\u00f6nnen wir deine Einwilligungen nicht verwalten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5efd82e e-flex e-con-boxed e-con e-parent\" data-id=\"5efd82e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-030877d e-flex e-con-boxed e-con e-child\" data-id=\"030877d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6989f66 elementor-widget elementor-widget-heading\" data-id=\"6989f66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">4. Weitere Funktionen und Angebote unserer Website<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e2fe711 e-flex e-con-boxed e-con e-child\" data-id=\"e2fe711\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5365d6e elementor-widget elementor-widget-text-editor\" data-id=\"5365d6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Neben der rein informatorischen Nutzung unserer Website bieten wir verschiedene Leistungen an, die Sie bei Interesse nutzen k\u00f6nnen. Dazu m\u00fcssen Sie in der Regel weitere personenbezogene Daten angeben, die wir zur Erbringung der jeweiligen Leistung nutzen und f\u00fcr die die zuvor genannten Grunds\u00e4tze zur Datenverarbeitung gelten.<\/p>\n<p>Teilweise bedienen wir uns zur Verarbeitung Ihrer Daten externer Dienstleister. Diese wurden von uns sorgf\u00e4ltig ausgew\u00e4hlt und beauftragt, sind an unsere Weisungen gebunden und werden regelm\u00e4\u00dfig kontrolliert.<\/p>\n<p>Weiterhin k\u00f6nnen wir Ihre personenbezogenen Daten an Dritte weitergeben, wenn Veranstaltungen, Vertragsabschl\u00fcsse oder \u00e4hnliche Leistungen von uns gemeinsam mit Partnern angeboten werden. N\u00e4here Informationen hierzu erhalten Sie bei Angabe Ihrer personenbezogenen Daten.<\/p>\n<p>Soweit unsere Dienstleister oder Partner ihren Sitz in einem Staat au\u00dferhalb des Europ\u00e4ischen Wirtschaftsraumen (EWR) haben, informieren wir Sie \u00fcber die Folgen dieses Umstands in der Beschreibung des Angebotes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c073fa7 e-flex e-con-boxed e-con e-parent\" data-id=\"c073fa7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b6ceafb e-flex e-con-boxed e-con e-child\" data-id=\"b6ceafb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bfbd659 elementor-widget elementor-widget-heading\" data-id=\"bfbd659\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">5. Widerspruch oder Widerruf gegen die Verarbeitung Ihrer Daten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-461b849 e-flex e-con-boxed e-con e-child\" data-id=\"461b849\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d2ef8cf elementor-widget elementor-widget-text-editor\" data-id=\"d2ef8cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Falls Sie eine Einwilligung zur Verarbeitung Ihrer Daten erteilt haben, k\u00f6nnen Sie diese jederzeit widerrufen. Ein solcher Widerruf beeinflusst die Zul\u00e4ssigkeit der Verarbeitung Ihrer personenbezogenen Daten, nachdem Sie ihn gegen\u00fcber uns ausgesprochen haben.<\/p>\n<p>Soweit wir die Verarbeitung Ihrer personenbezogenen Daten auf die Interessenabw\u00e4gung st\u00fctzen, k\u00f6nnen Sie Widerspruch gegen die Verarbeitung einlegen. Dies ist der Fall, wenn die Verarbeitung insbesondere nicht zur Erf\u00fcllung eines Vertrags mit Ihnen erforderlich ist, was von uns jeweils bei der nachfolgenden Beschreibung der Funktionen dargestellt wird. Bei Aus\u00fcbung eines solchen Widerspruchs bitten wir um Darlegung der Gr\u00fcnde, weshalb wir Ihre personenbezogenen Daten nicht wie von uns durchgef\u00fchrt verarbeiten sollten. Im Falle Ihres begr\u00fcndeten Widerspruchs pr\u00fcfen wir die Sachlage und werden entweder die Datenverarbeitung einstellen bzw. anpassen oder Ihnen unsere zwingenden schutzw\u00fcrdigen Gr\u00fcnde aufzeigen, aufgrund derer wir die Verarbeitung fortf\u00fchren.<\/p>\n<p>Selbstverst\u00e4ndlich k\u00f6nnen Sie der Verarbeitung Ihrer personenbezogenen Daten f\u00fcr Zwecke der Werbung und Datenanalyse jederzeit widersprechen. \u00dcber Ihren Werbewiderspruch k\u00f6nnen Sie uns unter den oben genannten Kontaktdaten informieren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2e0248a e-flex e-con-boxed e-con e-parent\" data-id=\"2e0248a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7f4c3bf e-flex e-con-boxed e-con e-child\" data-id=\"7f4c3bf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c2aced2 elementor-widget elementor-widget-heading\" data-id=\"c2aced2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">6. Einsatz von Google Analytics<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4d821fe e-flex e-con-boxed e-con e-child\" data-id=\"4d821fe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4a85449 elementor-widget elementor-widget-text-editor\" data-id=\"4a85449\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Diese Website benutzt Google Analytics, einen Webanalysedienst der Google Inc. (\u201eGoogle\u201c). Google Analytics verwendet sog. \u201eCookies\u201c, Textdateien, die auf Ihrem Computer gespeichert werden und die eine Analyse der Benutzung der Website durch Sie erm\u00f6glichen. Die durch den Cookie erzeugten Informationen \u00fcber Ihre Benutzung dieser Website werden in der Regel an einen Server von Google in den USA \u00fcbertragen und dort gespeichert. Ihre IP-Adresse wird von Google jedoch innerhalb von Mitgliedstaaten der Europ\u00e4ischen Union oder in anderen Vertragsstaaten des Abkommens \u00fcber den Europ\u00e4ischen Wirtschaftsraum zuvor gek\u00fcrzt. Nur in Ausnahmef\u00e4llen wird die volle IP-Adresse an einen Server von Google in den USA \u00fcbertragen und dort gek\u00fcrzt. Im Auftrag des Verantwortlichen dieser Website wird Google diese Informationen benutzen, um Ihre Nutzung der Website auszuwerten, um Reports \u00fcber die Website-Aktivit\u00e4ten zusammenzustellen und um weitere mit der Website-Nutzung und der Internetnutzung verbundene Dienstleistungen gegen\u00fcber dem Website-Verantwortlichen zu erbringen.<\/p>\n<p>Die im Rahmen von Google Analytics von Ihrem Browser \u00fcbermittelte IP-Adresse wird nicht mit anderen Daten von Google zusammengef\u00fchrt.<\/p>\n<p>Sie k\u00f6nnen die Speicherung der Cookies durch eine entsprechende Einstellung Ihrer Browser-Software verhindern; wir weisen Sie jedoch darauf hin, dass Sie in diesem Fall gegebenenfalls nicht s\u00e4mtliche Funktionen dieser Website vollumf\u00e4nglich werden nutzen k\u00f6nnen. Sie k\u00f6nnen dar\u00fcber hinaus die Erfassung der durch das Cookie erzeugten und auf Ihre Nutzung der Website bezogenen Daten (inkl. Ihrer IP-Adresse) an Google sowie die Verarbeitung dieser Daten durch Google verhindern, indem sie das unter dem folgenden Link verf\u00fcgbare Browser-Plug-in herunterladen und installieren:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ccf287 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5ccf287\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0fd2e6 elementor-widget elementor-widget-text-editor\" data-id=\"b0fd2e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Sie k\u00f6nnen schlie\u00dflich der Erfassung und Verarbeitung der auf Ihre Nutzung der Website bezogenen Daten durch Google verhindern, indem Sie diesen Link klicken; in diesem Fall wird in Ihrem Browser ein sog. Opt-Out-Cookie abgelegt, was zur Folge hat, dass Google keinerlei Sitzungsdaten erhebt. Bitte beachten Sie: Wenn Sie Ihre Cookies l\u00f6schen, so hat dies zur Folge, dass auch das Opt-Out-Cookie gel\u00f6scht wird und ggf. von Ihnen erneut aktiviert werden muss.<\/p>\n<p>Diese Website verwendet Google Analytics mit der Erweiterung \u201e_anonymizeIp()\u201c. Dadurch werden IP-Adressen gek\u00fcrzt weiterverarbeitet, eine Personenbeziehbarkeit kann damit ausgeschlossen werden. Soweit den \u00fcber Sie erhobenen Daten ein Personenbezug zukommt, wird dieser also sofort ausgeschlossen und die personenbezogenen Daten damit umgehend gel\u00f6scht.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-099d250 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"099d250\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.privacyshield.gov\/participant?id=a2zt000000001L5AAI&#038;status=Active\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M9.85901 16.6929L9.04901 17.498C8.70968 17.832 8.25264 18.0192 7.77651 18.0192C7.30038 18.0192 6.84334 17.832 6.50401 17.498C6.33856 17.3341 6.20723 17.1391 6.1176 16.9242C6.02797 16.7093 5.98182 16.4788 5.98182 16.2459C5.98182 16.0131 6.02797 15.7826 6.1176 15.5677C6.20723 15.3528 6.33856 15.1578 6.50401 14.9939L9.48401 12.0389C10.101 11.4259 11.263 10.5238 12.11 11.3639C12.2012 11.4611 12.3109 11.5389 12.4328 11.5927C12.5547 11.6465 12.6862 11.6753 12.8194 11.6772C12.9527 11.6791 13.0849 11.6541 13.2083 11.6038C13.3317 11.5534 13.4436 11.4788 13.5375 11.3842C13.6314 11.2896 13.7053 11.1771 13.7547 11.0534C13.8042 10.9297 13.8282 10.7973 13.8254 10.664C13.8225 10.5308 13.7929 10.3995 13.7382 10.278C13.6835 10.1565 13.6048 10.0473 13.507 9.95683C12.069 8.52881 9.94101 8.79281 8.08801 10.6318L5.10801 13.5879C4.7559 13.935 4.47655 14.3489 4.28631 14.8053C4.09606 15.2617 3.99873 15.7515 4.00001 16.2459C3.99878 16.7404 4.09614 17.2301 4.28638 17.6865C4.47663 18.1429 4.75595 18.5568 5.10801 18.904C5.81771 19.6079 6.7774 20.002 7.77701 20C8.74401 20 9.71101 19.635 10.446 18.904L11.257 18.099C11.3495 18.0075 11.423 17.8987 11.4733 17.7787C11.5237 17.6588 11.5498 17.5301 11.5503 17.4C11.5507 17.2699 11.5255 17.141 11.476 17.0207C11.4266 16.9004 11.3538 16.7911 11.262 16.6989C11.0764 16.5128 10.8246 16.4077 10.5617 16.4066C10.2989 16.4054 10.0462 16.5084 9.85901 16.6929V16.6929ZM18.891 5.20876C17.344 3.67473 15.182 3.59173 13.752 5.01175L12.743 6.01377C12.5566 6.19889 12.4513 6.4505 12.4503 6.71325C12.4494 6.97599 12.5529 7.22834 12.738 7.41479C12.9231 7.60124 13.1747 7.70652 13.4375 7.70745C13.7002 7.70839 13.9526 7.60492 14.139 7.41979L15.149 6.41878C15.889 5.68276 16.86 5.98777 17.495 6.61578C17.831 6.95078 18.017 7.39479 18.017 7.8678C18.017 8.34081 17.831 8.78481 17.495 9.11882L14.315 12.2729C12.861 13.7139 12.179 13.0389 11.888 12.7499C11.7957 12.6582 11.6862 12.5856 11.5658 12.5363C11.4455 12.4869 11.3166 12.4618 11.1865 12.4622C11.0564 12.4627 10.9276 12.4888 10.8076 12.539C10.6876 12.5892 10.5787 12.6626 10.487 12.7549C10.3953 12.8472 10.3228 12.9567 10.2734 13.077C10.224 13.1974 10.1989 13.3263 10.1993 13.4564C10.1998 13.5865 10.2259 13.7153 10.2761 13.8353C10.3263 13.9553 10.3997 14.0642 10.492 14.1559C11.16 14.8179 11.922 15.1459 12.72 15.1459C13.697 15.1459 14.73 14.6539 15.713 13.6789L18.893 10.5258C19.2443 10.1782 19.5231 9.76417 19.7132 9.30788C19.9032 8.85158 20.0007 8.36209 20 7.8678C20.0009 7.37316 19.9033 6.88328 19.7129 6.42675C19.5225 5.97022 19.2431 5.55618 18.891 5.20876V5.20876Z\" fill=\"#333333\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">https:\/\/www.privacyshield.gov\/participant?id=a2zt000000001L5AAI&amp;status=Active<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8643566 elementor-widget elementor-widget-text-editor\" data-id=\"8643566\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Rechtsgrundlage f\u00fcr die Nutzung von Google Analytics ist Art. 6 Abs. 1 S. 1 lit. f DS-GVO.<\/p>\n<p>Informationen des Drittanbieters: Google LLC, 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA, Tel: +1 650 253 0000, E-Mail:\u00a0<a href=\"mailto:support-de@google.com\" target=\"_blank\" rel=\"nofollow noopener\">support-de@google.com<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c39fd1 elementor-icon-list--layout-inline elementor-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3c39fd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.google.com\/analytics\/terms\/de.html\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Nutzerbedingungen<\/b>: http:\/\/www.google.com\/analytics\/terms\/de.html<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.google.com\/intl\/de\/analytics\/learn\/privacy.html\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>\u00dcbersicht zum Datenschutz<\/b>: http:\/\/www.google.com\/intl\/de\/analytics\/learn\/privacy.html<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.google.de\/intl\/de\/policies\/privacy\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Datenschutzerkl\u00e4rung<\/b>: http:\/\/www.google.de\/intl\/de\/policies\/privacy<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Table of Contents 1. Information \u00fcber die Erhebung personenbezogener Daten. Verantwortlicher gem. Art. 4 Abs. 7 der europ\u00e4ischen Datenschutz-Grundverordnung (DSGVO) ist: Stroschein &#038; Makowka Rechtsanw\u00e4lte PartG mbB F\u00fcrstenwall 172 F\u00fcrst &#038; Friedrich40217 D\u00fcsseldorf info@smr-legal.de +49 211 698050-33 (nachfolgend \u201eS&amp;M\u201c oder \u201ewir\u201c) Bei Ihrer Kontaktaufnahme mit uns per E-Mail werden die von Ihnen mitgeteilten Daten (Ihre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":281,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Datenschutzerkl\u00e4rung - Stroschein &amp; Makowka<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smr-legal.de\/ru\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutzerkl\u00e4rung - Stroschein &amp; Makowka\" \/>\n<meta property=\"og:description\" content=\"Table of Contents 1. Information \u00fcber die Erhebung personenbezogener Daten. Verantwortlicher gem. Art. 4 Abs. 7 der europ\u00e4ischen Datenschutz-Grundverordnung (DSGVO) ist: Stroschein &#038; Makowka Rechtsanw\u00e4lte PartG mbB F\u00fcrstenwall 172 F\u00fcrst &#038; Friedrich40217 D\u00fcsseldorf info@smr-legal.de +49 211 698050-33 (nachfolgend \u201eS&amp;M\u201c oder \u201ewir\u201c) Bei Ihrer Kontaktaufnahme mit uns per E-Mail werden die von Ihnen mitgeteilten Daten (Ihre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smr-legal.de\/ru\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:site_name\" content=\"Stroschein &amp; Makowka\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/StroscheinMakowka\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-06T00:02:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smr-legal.de\/wp-content\/uploads\/2024\/04\/stroschein-makowka-fuerst-und-friedrich-offices-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 \u043c\u0438\u043d\u0443\u0442\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smr-legal.de\\\/datenschutzerklaerung\\\/\",\"url\":\"https:\\\/\\\/smr-legal.de\\\/datenschutzerklaerung\\\/\",\"name\":\"Datenschutzerkl\u00e4rung - Stroschein &amp; Makowka\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smr-legal.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smr-legal.de\\\/datenschutzerklaerung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smr-legal.de\\\/datenschutzerklaerung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smr-legal.de\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/stroschein-makowka-fuerst-und-friedrich-offices-01.jpg\",\"datePublished\":\"2024-01-03T03:51:43+00:00\",\"dateModified\":\"2025-05-06T00:02:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smr-legal.de\\\/datenschutzerklaerung\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smr-legal.de\\\/datenschutzerklaerung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/smr-legal.de\\\/datenschutzerklaerung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smr-legal.de\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/stroschein-makowka-fuerst-und-friedrich-offices-01.jpg\",\"contentUrl\":\"https:\\\/\\\/smr-legal.de\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/stroschein-makowka-fuerst-und-friedrich-offices-01.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smr-legal.de\\\/datenschutzerklaerung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/smr-legal.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutzerkl\u00e4rung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smr-legal.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/smr-legal.de\\\/en\\\/\",\"name\":\"Stroschein & Makowka\",\"description\":\"Fachanw\u00e4lte f\u00fcr Handels- und Gesellschaftsrecht &amp; Internationales Wirtschaftsrecht\",\"publisher\":{\"@id\":\"https:\\\/\\\/smr-legal.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smr-legal.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/smr-legal.de\\\/en\\\/#organization\",\"name\":\"Stroschein & Makowka Partnerschaftsgesellschaft mbB\",\"url\":\"https:\\\/\\\/smr-legal.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/smr-legal.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/smr-legal.de\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logo-sm-gr.png\",\"contentUrl\":\"https:\\\/\\\/smr-legal.de\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logo-sm-gr.png\",\"width\":2200,\"height\":550,\"caption\":\"Stroschein & Makowka Partnerschaftsgesellschaft mbB\"},\"image\":{\"@id\":\"https:\\\/\\\/smr-legal.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/StroscheinMakowka\",\"https:\\\/\\\/www.instagram.com\\\/stroscheinmakowka\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutzerkl\u00e4rung - Stroschein &amp; Makowka","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smr-legal.de\/ru\/datenschutzerklaerung\/","og_locale":"ru_RU","og_type":"article","og_title":"Datenschutzerkl\u00e4rung - Stroschein &amp; Makowka","og_description":"Table of Contents 1. Information \u00fcber die Erhebung personenbezogener Daten. Verantwortlicher gem. Art. 4 Abs. 7 der europ\u00e4ischen Datenschutz-Grundverordnung (DSGVO) ist: Stroschein &#038; Makowka Rechtsanw\u00e4lte PartG mbB F\u00fcrstenwall 172 F\u00fcrst &#038; Friedrich40217 D\u00fcsseldorf info@smr-legal.de +49 211 698050-33 (nachfolgend \u201eS&amp;M\u201c oder \u201ewir\u201c) Bei Ihrer Kontaktaufnahme mit uns per E-Mail werden die von Ihnen mitgeteilten Daten (Ihre [&hellip;]","og_url":"https:\/\/smr-legal.de\/ru\/datenschutzerklaerung\/","og_site_name":"Stroschein &amp; Makowka","article_publisher":"https:\/\/www.facebook.com\/StroscheinMakowka","article_modified_time":"2025-05-06T00:02:12+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/smr-legal.de\/wp-content\/uploads\/2024\/04\/stroschein-makowka-fuerst-und-friedrich-offices-01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"10 \u043c\u0438\u043d\u0443\u0442"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/smr-legal.de\/datenschutzerklaerung\/","url":"https:\/\/smr-legal.de\/datenschutzerklaerung\/","name":"Datenschutzerkl\u00e4rung - Stroschein &amp; Makowka","isPartOf":{"@id":"https:\/\/smr-legal.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smr-legal.de\/datenschutzerklaerung\/#primaryimage"},"image":{"@id":"https:\/\/smr-legal.de\/datenschutzerklaerung\/#primaryimage"},"thumbnailUrl":"https:\/\/smr-legal.de\/wp-content\/uploads\/2024\/04\/stroschein-makowka-fuerst-und-friedrich-offices-01.jpg","datePublished":"2024-01-03T03:51:43+00:00","dateModified":"2025-05-06T00:02:12+00:00","breadcrumb":{"@id":"https:\/\/smr-legal.de\/datenschutzerklaerung\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smr-legal.de\/datenschutzerklaerung\/"]}]},{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/smr-legal.de\/datenschutzerklaerung\/#primaryimage","url":"https:\/\/smr-legal.de\/wp-content\/uploads\/2024\/04\/stroschein-makowka-fuerst-und-friedrich-offices-01.jpg","contentUrl":"https:\/\/smr-legal.de\/wp-content\/uploads\/2024\/04\/stroschein-makowka-fuerst-und-friedrich-offices-01.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/smr-legal.de\/datenschutzerklaerung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/smr-legal.de\/"},{"@type":"ListItem","position":2,"name":"Datenschutzerkl\u00e4rung"}]},{"@type":"WebSite","@id":"https:\/\/smr-legal.de\/en\/#website","url":"https:\/\/smr-legal.de\/en\/","name":"Stroschein & Makowka","description":"\u041f\u0440\u043e\u0444\u0435\u0441\u0441\u0438\u043e\u043d\u0430\u043b\u044c\u043d\u044b\u0435 \u0430\u0434\u0432\u043e\u043a\u0430\u0442\u044b \u0432 \u0441\u0444\u0435\u0440\u0435 \u043a\u043e\u043c\u043c\u0435\u0440\u0447\u0435\u0441\u043a\u043e\u0433\u043e \u0438 \u043a\u043e\u0440\u043f\u043e\u0440\u0430\u0442\u0438\u0432\u043d\u043e\u0433\u043e \u043f\u0440\u0430\u0432\u0430, \u0430 \u0442\u0430\u043a\u0436\u0435 \u043c\u0435\u0436\u0434\u0443\u043d\u0430\u0440\u043e\u0434\u043d\u043e\u0433\u043e \u0431\u0438\u0437\u043d\u0435\u0441 \u043f\u0440\u0430\u0432\u0430.","publisher":{"@id":"https:\/\/smr-legal.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smr-legal.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/smr-legal.de\/en\/#organization","name":"Stroschein &amp; Makowka Partnerschaftsgesellschaft mbB","url":"https:\/\/smr-legal.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/smr-legal.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/smr-legal.de\/wp-content\/uploads\/2024\/04\/logo-sm-gr.png","contentUrl":"https:\/\/smr-legal.de\/wp-content\/uploads\/2024\/04\/logo-sm-gr.png","width":2200,"height":550,"caption":"Stroschein & Makowka Partnerschaftsgesellschaft mbB"},"image":{"@id":"https:\/\/smr-legal.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/StroscheinMakowka","https:\/\/www.instagram.com\/stroscheinmakowka\/"]}]}},"_links":{"self":[{"href":"https:\/\/smr-legal.de\/ru\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smr-legal.de\/ru\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/smr-legal.de\/ru\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/smr-legal.de\/ru\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smr-legal.de\/ru\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":21,"href":"https:\/\/smr-legal.de\/ru\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":2169,"href":"https:\/\/smr-legal.de\/ru\/wp-json\/wp\/v2\/pages\/3\/revisions\/2169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smr-legal.de\/ru\/wp-json\/wp\/v2\/media\/281"}],"wp:attachment":[{"href":"https:\/\/smr-legal.de\/ru\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}